{"id":539,"count":34,"description":"","link":"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/","name":"Four Seasons chefs","slug":"four-seasons-chefs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Four Seasons chefs Archives - Four Seasons Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Four Seasons chefs Archives - Four Seasons Magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/\" \/>\n<meta property=\"og:site_name\" content=\"Four Seasons Magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/tag\\\/four-seasons-chefs\\\/\",\"url\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/tag\\\/four-seasons-chefs\\\/\",\"name\":\"Four Seasons chefs Archives - Four Seasons Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#website\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/\",\"name\":\"Four Seasons Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#organization\",\"name\":\"Four Seasons Magazine\",\"url\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/FS-mag-logo-v2.svg\",\"contentUrl\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/FS-mag-logo-v2.svg\",\"caption\":\"Four Seasons Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fourseasons.com\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Four Seasons chefs Archives - Four Seasons Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/","og_locale":"en_GB","og_type":"article","og_title":"Four Seasons chefs Archives - Four Seasons Magazine","og_url":"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/","og_site_name":"Four Seasons Magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/","url":"https:\/\/www.fourseasons.com\/magazine\/tag\/four-seasons-chefs\/","name":"Four Seasons chefs Archives - Four Seasons Magazine","isPartOf":{"@id":"https:\/\/www.fourseasons.com\/magazine\/#website"},"inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/www.fourseasons.com\/magazine\/#website","url":"https:\/\/www.fourseasons.com\/magazine\/","name":"Four Seasons Magazine","description":"","publisher":{"@id":"https:\/\/www.fourseasons.com\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fourseasons.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.fourseasons.com\/magazine\/#organization","name":"Four Seasons Magazine","url":"https:\/\/www.fourseasons.com\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.fourseasons.com\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/www.fourseasons.com\/magazine\/wp-content\/uploads\/2025\/06\/FS-mag-logo-v2.svg","contentUrl":"https:\/\/www.fourseasons.com\/magazine\/wp-content\/uploads\/2025\/06\/FS-mag-logo-v2.svg","caption":"Four Seasons Magazine"},"image":{"@id":"https:\/\/www.fourseasons.com\/magazine\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fourseasons.com\/magazine\/wp-json\/wp\/v2\/tags\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fourseasons.com\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fourseasons.com\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fourseasons.com\/magazine\/wp-json\/wp\/v2\/posts?tags=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}